{"id":173,"date":"2018-09-11T17:21:46","date_gmt":"2018-09-11T17:21:46","guid":{"rendered":"http:\/\/bifrost.local\/?page_id=173"},"modified":"2018-09-11T17:21:46","modified_gmt":"2018-09-11T17:21:46","slug":"blog-boxed-grid","status":"publish","type":"page","link":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/blog-boxed-grid\/","title":{"rendered":"Blog Boxed Grid"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"173\" class=\"elementor elementor-173\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec86fce elementor-section-boxed elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"ec86fce\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c7ba920\" data-id=\"c7ba920\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e65472 h-offset--no elementor-widget elementor-widget-neuron-posts\" data-id=\"9e65472\" data-element_type=\"widget\" data-widget_type=\"neuron-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"l-posts-wrapper l-filters-holder l-posts-wrapper--meta-outside h-overflow-hidden l-blog-wrapper\" data-posts=\"9e65472\">\n\t\t\t\t\t\t\t\t\t<div class=\"l-blog-wrapper__posts-holder l-blog-wrapper__posts-holder--meta-outside h-overflow-hidden\">\n\t\t\t\t    <div class=\"row masonry\" data-masonry-id=\"3f763c0deb0f6acdeb181a5f15b60d98\">\n                                <div class=\"selector col-lg-4 apps social tech post-6683 post type-post status-publish format-standard has-post-thumbnail hentry category-apps category-social category-tech tag-startups tag-enterprise tag-developers\" data-id=\"6683\" data-columns=\"3-columns\">\n                <div class=\"o-post o-blog-post wow h-fadeInUpNeuron\" >\n                        <div class=\"o-neuron-hover o-neuron-hover--icon o-neuron-hover--scale\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                                            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/google-cloud\/\" class=\"o-neuron-hover-holder__header__media\">\n                            <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder.png\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder.png 1000w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-300x300.png 300w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-100x100.png 100w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-600x600.png 600w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-150x150.png 150w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-768x768.png 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                            <\/div>\n                        <\/a>\n                                                                        <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                            <\/div>\n                            <div class=\"o-neuron-hover-holder__body d-flex\">\n                    <div class=\"o-neuron-hover-holder__body__inner\">\n                        <div class=\"o-neuron-hover-holder__body-meta o-neuron__post-icon\">\n                                                    <\/div>\n                    <\/div>\n                    <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/google-cloud\/\"><\/a>\n                <\/div>\n                     <\/div>\n    <\/div>\n<div class=\"o-blog-post__content o-neuron-post__content\">\n            <div class=\"o-blog-post__meta\">\n            <span class=\"o-blog-post__time a-separator o-neuron-post__meta-icon\">\n        <span class=\"o-neuron-post__meta\">16 octobre 2018<\/span>\n<\/span>        <\/div>\n                <h4 class=\"o-blog-post__title o-neuron-post__title\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/google-cloud\/\">Google Cloud<\/a>\n        <\/h4>\n        <p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Quisque posuere consequat nisl a sagittis. Maecenas euismod nunc eget&#8230;<\/p>\n<div class=\"o-blog-post__author d-flex align-items-center\">\n            <div class=\"avatar\">\n            <img alt='' src='https:\/\/secure.gravatar.com\/avatar\/9fcfe66996b1a6f1b740cfdcdfb6cdad?s=32&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/9fcfe66996b1a6f1b740cfdcdfb6cdad?s=64&#038;d=mm&#038;r=g 2x' class='avatar avatar-32 photo' height='32' width='32' \/>        <\/div>\n        <div class=\"author-name\">\n        <a class=\"o-neuron-post__author\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/author\/bruno\/\" title=\"Articles par Bruno\" rel=\"author\">Bruno<\/a>    <\/div>\n<\/div><\/div>                <\/div>\n            <\/div>\n            <\/div>\n\n\n\n\n\t\t\t<\/div>\n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>October 1, 2018 Torridon Lorem ipsum dolor sit amet, consectetur adipiscing elit. Quisque posuere consequat nisl a sagittis&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 15:40:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":""},"_links":{"self":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages\/173"}],"collection":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/comments?post=173"}],"version-history":[{"count":0,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages\/173\/revisions"}],"wp:attachment":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/media?parent=173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}