{"id":179,"date":"2018-09-11T17:22:37","date_gmt":"2018-09-11T17:22:37","guid":{"rendered":"http:\/\/bifrost.local\/?page_id=179"},"modified":"2018-09-11T17:22:37","modified_gmt":"2018-09-11T17:22:37","slug":"blog-boxed-sidebar","status":"publish","type":"page","link":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/blog-boxed-sidebar\/","title":{"rendered":"Blog Boxed Sidebar"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"179\" class=\"elementor elementor-179\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bd4344 elementor-section-boxed elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"2bd4344\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-df5a08c\" data-id=\"df5a08c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67b9bd2 h-offset--no elementor-widget elementor-widget-neuron-posts\" data-id=\"67b9bd2\" data-element_type=\"widget\" data-widget_type=\"neuron-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"l-posts-wrapper l-filters-holder l-posts-wrapper--meta-outside h-overflow-hidden l-blog-wrapper\" data-posts=\"67b9bd2\">\n\t\t\t\t\t\t\t\t\t<div class=\"l-blog-wrapper__posts-holder l-blog-wrapper__posts-holder--meta-outside h-overflow-hidden\">\n\t\t\t\t    <div class=\"row masonry\" data-masonry-id=\"f7cbed5c9583ec1d9c8b39c190bc7e59\">\n                                <div class=\"selector col-lg-6 apps social tech post-6683 post type-post status-publish format-standard has-post-thumbnail hentry category-apps category-social category-tech tag-startups tag-enterprise tag-developers\" data-id=\"6683\" data-columns=\"2-columns\">\n                <div class=\"o-post o-blog-post wow h-fadeInUpNeuron\" >\n                        <div class=\"o-neuron-hover o-neuron-hover--icon o-neuron-hover--scale\">\n        <div class=\"o-neuron-hover-holder\">\n            <div class=\"o-neuron-hover-holder__header\">\n                                                            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/google-cloud\/\" class=\"o-neuron-hover-holder__header__media\">\n                            <div class=\"h-calculated-image\" style=\"padding-bottom: 100.000000% !important;\">\n                                <img decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder.png\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" srcset=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder.png 1000w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-300x300.png 300w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-100x100.png 100w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-600x600.png 600w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-150x150.png 150w, https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/08\/placeholder-768x768.png 768w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>                            <\/div>\n                        <\/a>\n                                                                        <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                            <\/div>\n                            <div class=\"o-neuron-hover-holder__body d-flex\">\n                    <div class=\"o-neuron-hover-holder__body__inner\">\n                        <div class=\"o-neuron-hover-holder__body-meta o-neuron__post-icon\">\n                                                    <\/div>\n                    <\/div>\n                    <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/google-cloud\/\"><\/a>\n                <\/div>\n                     <\/div>\n    <\/div>\n<div class=\"o-blog-post__content o-neuron-post__content\">\n            <div class=\"o-blog-post__meta\">\n            <span class=\"o-blog-post__time a-separator o-neuron-post__meta-icon\">\n        <span class=\"o-neuron-post__meta\">16 octobre 2018<\/span>\n<\/span>        <\/div>\n                <h4 class=\"o-blog-post__title o-neuron-post__title\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/google-cloud\/\">Google Cloud<\/a>\n        <\/h4>\n        <p>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Quisque posuere consequat nisl a sagittis. Maecenas euismod nunc eget&#8230;<\/p>\n<div class=\"o-blog-post__author d-flex align-items-center\">\n            <div class=\"avatar\">\n            <img alt='' src='https:\/\/secure.gravatar.com\/avatar\/9fcfe66996b1a6f1b740cfdcdfb6cdad?s=32&#038;d=mm&#038;r=g' srcset='https:\/\/secure.gravatar.com\/avatar\/9fcfe66996b1a6f1b740cfdcdfb6cdad?s=64&#038;d=mm&#038;r=g 2x' class='avatar avatar-32 photo' height='32' width='32' \/>        <\/div>\n        <div class=\"author-name\">\n        <a class=\"o-neuron-post__author\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/author\/bruno\/\" title=\"Articles par Bruno\" rel=\"author\">Bruno<\/a>    <\/div>\n<\/div><\/div>                <\/div>\n            <\/div>\n            <\/div>\n\n\n\n\n\t\t\t<\/div>\n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8193b27\" data-id=\"8193b27\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de6ab27 elementor-widget elementor-widget-sidebar\" data-id=\"de6ab27\" data-element_type=\"widget\" data-widget_type=\"sidebar.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div id=\"search-2\" class=\"widget widget_search\"><form action=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/\" method=\"get\">\n    <input placeholder=\"Search...\" type=\"search\" name=\"s\" id=\"search\" \/>\n<\/form>\n<\/div>\n\t\t<div id=\"recent-posts-2\" class=\"widget widget_recent_entries\">\n\t\t<div class=\"widgettitle-wrapper\"><h5 class=\"widgettitle\">Nos formations<\/h5><\/div>\n\t\t<ul>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/outlooktechniques-avancees3h-150e\/\">Outlook<br>Techniques avanc\u00e9es<br>3h-150\u20ac<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/outlook-pour-les-nuls-le-22-avril\/\">Outlook pour les nuls<br>3h-150\u20ac<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/word-pour-les-nuls-le-18-avril\/\">Word pour les nuls<br> 6h &#8211; 250\u20ac<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/powerpoint-avancele-18-avril\/\">Powerpoint<br> Techniques avanc\u00e9es<br>6h &#8211; 250\u20ac<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li>\n\t\t\t\t\t<a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/powerpointpour-les-nuls6h-250e\/\">Powerpoint<br>pour les nuls<br>6h &#8211; 250\u20ac<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t<\/ul>\n\n\t\t<\/div><div id=\"recent-comments-2\" class=\"widget widget_recent_comments\"><div class=\"widgettitle-wrapper\"><h5 class=\"widgettitle\">Commentaires r\u00e9cents<\/h5><\/div><ul id=\"recentcomments\"><\/ul><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>October 1, 2018 Torridon Lorem ipsum dolor sit amet, consectetur adipiscing elit. Quisque posuere consequat nisl a sagittis&#8230;.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":23,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 14:58:11","action":"change-status","newStatus":"draft","terms":[],"taxonomy":""},"_links":{"self":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages\/179"}],"collection":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/comments?post=179"}],"version-history":[{"count":0,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages\/179\/revisions"}],"wp:attachment":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/media?parent=179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}