{"id":21569,"date":"2019-05-22T16:27:37","date_gmt":"2019-05-22T16:27:37","guid":{"rendered":"http:\/\/bifrost.local\/?page_id=21569"},"modified":"2019-05-22T16:27:37","modified_gmt":"2019-05-22T16:27:37","slug":"personal-portfolio","status":"publish","type":"page","link":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/personal-portfolio\/","title":{"rendered":"Personal Portfolio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"21569\" class=\"elementor elementor-21569\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fb5b0d elementor-section-boxed elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"9fb5b0d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3855be0\" data-id=\"3855be0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa751cb h-offset--no elementor-widget elementor-widget-neuron-posts\" data-id=\"fa751cb\" data-element_type=\"widget\" data-widget_type=\"neuron-posts.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"l-posts-wrapper l-filters-holder l-posts-wrapper--meta-inside h-overflow-hidden l-portfolio-wrapper\" data-posts=\"fa751cb\">\n\t\t\t\t\t\t\t\t\t<div class=\"l-portfolio-wrapper__items-holder l-portfolio-wrapper__items-holder--meta-inside h-overflow-hidden\">\n\t\t\t\t    <div class=\"row masonry\" data-masonry-id=\"44050461aa2a30dcef8db811b4c7b8ba\">\n                                <div class=\"selector col-lg-3 branding post-28728 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-branding\" data-id=\"28728\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" >\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v8\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 71.428571% !important;\">\n                        <img decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/07\/1e6bc211a5467701106fda0e6974254f-scaled-e1629721304473-560x400.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" \/>                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v8\/\">Adobe Illustrator<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/branding\/\">Branding<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v8\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 branding post-28704 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-branding\" data-id=\"28704\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=0.2s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v8\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 120.845921% !important;\">\n                        <img decoding=\"async\" width=\"331\" height=\"400\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/07\/unnamed-331x400.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" \/>                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v8\/\">Vertical Portfolio v8<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/branding\/\">Branding<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v8\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 creative post-28663 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-creative\" data-id=\"28663\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=0.4s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v4\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 71.428571% !important;\">\n                        <img decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2019\/07\/483421189a9d44bb15623e6e9a3bc2f4-560x400.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" \/>                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v4\/\">Vertical Portfolio v4<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/creative\/\">Creative<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v4\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 design post-28618 portfolio type-portfolio status-publish hentry portfolio_category-design\" data-id=\"28618\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=0.6s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v5\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100%;\">\n                        <img decoding=\"async\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/themes\/bifrost\/assets\/images\/placeholder.png\" alt=\"Placeholder Image\">\n                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v5\/\">Side Portfolio v5<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/design\/\">Design<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v5\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 creative post-3509 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-creative\" data-id=\"3509\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=0.8s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v2\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 71.428571% !important;\">\n                        <img decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2018\/09\/881415294f_50170557_code-html-sashkin-adobe-stock-560x400.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" \/>                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v2\/\">Side Portfolio v2<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/creative\/\">Creative<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v2\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 creative post-3370 portfolio type-portfolio status-publish hentry portfolio_category-creative\" data-id=\"3370\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=1s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v3\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100%;\">\n                        <img decoding=\"async\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/themes\/bifrost\/assets\/images\/placeholder.png\" alt=\"Placeholder Image\">\n                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v3\/\">Vertical Portfolio v3<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/creative\/\">Creative<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v3\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 branding post-3471 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-branding\" data-id=\"3471\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" >\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v1\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 71.428571% !important;\">\n                        <img decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2018\/09\/91WuW1UkhlL._AC_-560x400.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" \/>                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v1\/\">Side Portfolio v1<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/branding\/\">Branding<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v1\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 design post-3523 portfolio type-portfolio status-publish hentry portfolio_category-design\" data-id=\"3523\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=0.2s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v2\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100%;\">\n                        <img decoding=\"async\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/themes\/bifrost\/assets\/images\/placeholder.png\" alt=\"Placeholder Image\">\n                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v2\/\">Vertical Portfolio v2<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/design\/\">Design<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v2\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 branding post-3307 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-branding\" data-id=\"3307\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=0.4s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v3\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 71.428571% !important;\">\n                        <img decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2018\/09\/d050e376818901.5c93cd274cf10-1-560x400.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" \/>                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v3\/\">Side Portfolio v3<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/branding\/\">Branding<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v3\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 branding post-3343 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio_category-branding\" data-id=\"3343\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=0.6s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v4\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 71.428571% !important;\">\n                        <img decoding=\"async\" width=\"560\" height=\"400\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/uploads\/2018\/09\/0833_VI_2001_WELL_COVER2_PAOLO_VENTURA-560x400.jpg\" class=\"attachment-bifrost_image_size_1 size-bifrost_image_size_1 wp-post-image\" alt=\"\" \/>                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v4\/\">Side Portfolio v4<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/branding\/\">Branding<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v4\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 creative post-3405 portfolio type-portfolio status-publish hentry portfolio_category-creative\" data-id=\"3405\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=0.8s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v6\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100%;\">\n                        <img decoding=\"async\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/themes\/bifrost\/assets\/images\/placeholder.png\" alt=\"Placeholder Image\">\n                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v6\/\">Vertical Portfolio v6<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/creative\/\">Creative<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/vertical-portfolio-v6\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n                                <div class=\"selector col-lg-3 design post-3420 portfolio type-portfolio status-publish hentry portfolio_category-design\" data-id=\"3420\" data-columns=\"4-columns\">\n                <div class=\"o-post o-portfolio-item wow h-zoomInNeuron\" data-wow-delay=1s>\n                    <div class=\"o-neuron-hover o-neuron-hover--meta-inside o-neuron-hover--scale\">\n    <div class=\"o-neuron-hover-holder\">\n        <div class=\"o-neuron-hover-holder__header\">\n            <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v6\/\" class=\"o-neuron-hover-holder__header__media\">\n                                    <div class=\"h-calculated-image\" style=\"padding-bottom: 100%;\">\n                        <img decoding=\"async\" src=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-content\/themes\/bifrost\/assets\/images\/placeholder.png\" alt=\"Placeholder Image\">\n                    <\/div>\n                            <\/a>\n                            <div class=\"o-neuron-hover-holder__header__overlay\"><\/div>\n                    <\/div>\n                    <div class=\"o-neuron-hover-holder__body d-flex align-items-center\">\n                <div class=\"o-neuron-hover-holder__body__inner\">\n                    <div class=\"o-neuron-hover-holder__body-meta\">\n                                                    <h4 class=\"o-neuron-hover-holder__body-meta__title o-neuron-post__title\"><a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v6\/\">Side Portfolio v6<\/a><\/h4>\n                                                                            <div class=\"o-portfolio-item__category-holder o-neuron-post__meta\">\n    <div class=\"o-portfolio-item__category a-separator o-neuron-post__meta-icon\">\n                <ul>\n                            <li><a class=\"o-neuron-post__meta\" href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio_category\/design\/\">Design<\/a><\/li>\n                    <\/ul>\n    <\/div>\n<\/div>                                            <\/div>\n                <\/div>\n                <a href=\"https:\/\/lesmangeursdetoiles.org\/mangeurs\/portfolio\/side-portfolio-v6\/\"><\/a>\n            <\/div>\n            <\/div>\n<\/div>                <\/div>\n            <\/div>\n            <\/div>\n\n\n<div class='o-pagination'><div class='container'><div class='row align-items-center h-medium-top-padding h-medium-bottom-padding'><div class='o-pagination__arrow d-inline-flex col-2 o-pagination__arrow--disabled'><a class=\"bifrost-link d-inline-flex\" href='https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages\/21569\/'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='22' height='22' viewBox='0 0 24 24' fill='none' stroke-width='2' stroke-linecap='round' stroke-linejoin='round' class='feather feather-chevron-left'><polyline points='15 18 9 12 15 6'><\/polyline><\/svg><\/a><\/div><ul class='col-8 h-align-center o-pagination__numbers'><li class=\"active\"><a>1<\/a><\/li><li><a href='https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages\/21569\/page\/2\/' class=\"inactive bifrost-link\">2<\/a><\/li><\/ul><div class='o-pagination__arrow d-inline-flex col-2'><a class=\"bifrost-link d-inline-flex ml-auto\" href='https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages\/21569\/page\/2\/'><svg xmlns='http:\/\/www.w3.org\/2000\/svg' width='22' height='22' viewBox='0 0 24 24' fill='none' stroke-width='2' stroke-linecap='round' stroke-linejoin='round' class='feather feather-chevron-right'><polyline points='9 18 15 12 9 6'><\/polyline><\/svg><\/a><\/div><\/div><\/div><\/div>\n\n\n\t\t\t<\/div>\n        <\/div>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Side Portfolio v8 Branding Vertical Portfolio v8 Branding Vertical Portfolio v4 Creative Side Portfolio v5 Design Side Portfolio&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":81,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 14:58:40","action":"change-status","newStatus":"draft","terms":[],"taxonomy":""},"_links":{"self":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages\/21569"}],"collection":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/comments?post=21569"}],"version-history":[{"count":0,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/pages\/21569\/revisions"}],"wp:attachment":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/media?parent=21569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}