{"id":87,"date":"2020-11-10T21:40:02","date_gmt":"2020-11-10T21:40:02","guid":{"rendered":"http:\/\/www.mangeursdetoiles.com\/accueil\/?p=87"},"modified":"2021-09-06T15:36:55","modified_gmt":"2021-09-06T13:36:55","slug":"indesign","status":"publish","type":"post","link":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/indesign\/","title":{"rendered":"Adobe Indesign base &#8211; Les 24, 26 et 27 ao\u00fbt de 9h30 \u00e0 16h30"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"87\" class=\"elementor elementor-87\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94fa01c elementor-section-boxed elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"94fa01c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ddf6b47\" data-id=\"ddf6b47\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-31aebfe elementor-section-boxed elementor-section-height-default elementor-section-height-default neuron-fixed-no\" data-id=\"31aebfe\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17267bf\" data-id=\"17267bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-df9642f elementor-widget elementor-widget-text-editor\" data-id=\"df9642f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.16.0 - 20-09-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div><strong>Indesign<\/strong> est un programme qui, utilis\u00e9 conjointement avec Illustrator et Photoshop, permet de r\u00e9aliser des travaux destin\u00e9s aussi bien au monde de l&#8217;\u00e9dition, du graphisme ou de de la communication publicitaire. Indesign permet de r\u00e9aliser facilement des mises en page magazine, des livres, des brochures, des d\u00e9pliants mais aussi des ebook ainsi que des newsletters interactives.<\/div><p>\u00a0<\/p><h1><a href=\"http:\/\/www.mangeursdetoiles.com\/accueil\/wp-content\/uploads\/2012\/05\/cosmo-jun-2010-pic5.jpg\"><img decoding=\"async\" src=\"http:\/\/www.mangeursdetoiles.com\/accueil\/wp-content\/uploads\/2012\/05\/cosmo-jun-2010-pic5-229x300.jpg\" alt=\"cosmopolitan cover\" width=\"229\" height=\"300\" \/><\/a><\/h1><p>\u00a0<\/p><h2><strong>3 jours de formation <br \/>Pour module base et interm\u00e9diaire <br \/>2 jours pour le module avanc\u00e9<\/strong><\/h2><p><strong>Niveaux requis :<\/strong><br \/>Une bonne connaissance de l\u2019outil informatique\u00a0<\/p><h1>LES BASES : PROGRAMME DE COURS<\/h1><p>\u00a0<\/p><ul><li>G\u00e9n\u00e9ralit\u00e9s<\/li><li>Affichage (zooms, palettes, outils, rep\u00e8res, grilles, pr\u00e9f\u00e9rences)<\/li><li>Compositions (pages, pages type, utilisation des calques)<\/li><li>Texte (gestion du texte, les styles, importation, formatage, conseils pratiques, tabulations, vectorisation texte)<\/li><li>Placer le texte en colonnes, utilisation des grilles d&#8217;alignement<\/li><li>Tableaux (Cr\u00e9ation et modification de tableaux, mise en forme)<\/li><li>Cr\u00e9ation de trac\u00e9s vectoriels (placer du texte sur un vecteur, tra\u00e7age des courbes de bezier)<\/li><li>Importer des images (formats, r\u00e9solutions suivant le type d&#8217;impression, notions indispensables de photogravure, affichage, transparences)<\/li><li>Gestions de &#8220;livres&#8221; (documents longs, num\u00e9rotation, sections, maquettes)<\/li><li>Cr\u00e9er plusieurs gabarits.<\/li><li>Colorisation (cmyk, rgb, bichromie, niveaux de gris, s\u00e9paration des couleurs, gestion des d\u00e9fonces)<\/li><li>Impression, diffusion et exportation<\/li><li>d\u00e9tourage et habillage<\/li><\/ul><h1>\u00a0<\/h1><h1>TECHNIQUES AVANCEES<\/h1><p>Diff\u00e9rents exercices de mise en condition sur des cas pratiques seront propos\u00e9s afin de v\u00e9rifier et consolider les acquis du cours pr\u00e9c\u00e9dent. Le cours avanc\u00e9 est ax\u00e9 sur les fonctions li\u00e9es \u00e0 l\u2019\u00e9dition, \u00e0 la cr\u00e9ation de documents longs, \u00e0 la cr\u00e9ation de documents num\u00e9riques interactifs, aux fonctions avanc\u00e9es de photogravure et aux relations entre Photoshop, Illustrator et Indesign.<\/p><p><strong>Niveaux requis :<\/strong>\u00a0Avoir suivi le cours de base ou avoir un niveau \u00e9quivalent.<br \/>Une bonne connaissance de l\u2019outil informatique\u00a0<\/p><h2>PROGRAMME DE COURS<\/h2><h2>\u00a0<\/h2><ul><li>Utiliser les styles de Paragraphes et de Caract\u00e8res<\/li><li>Cr\u00e9er des styles imbriqu\u00e9s<\/li><li>Appliquer des styles diff\u00e9rents \u00e0 l\u2019ensemble d\u2019une s\u00e9lection<\/li><li>Cr\u00e9ation de tables de mati\u00e8res automatiques<\/li><li>G\u00e9n\u00e9ration de glossaires et d\u2019index<\/li><li>Gestion et cr\u00e9ation d\u2019\u00e9l\u00e9ments interactifs<\/li><li>Gestion des noirs et calibrage colorim\u00e9trique<\/li><li>Aper\u00e7u de la sortie, de l\u2019aplatissement et de la surimpression<\/li><li>Importer et pr\u00e9visualiser des profils ICC<\/li><li>Cr\u00e9er des d\u00e9pliants complexes avec l outil Page<\/li><li>Fonctions avanc\u00e9es de d\u00e9tourages et d\u2019habillage<\/li><li>Utiliser les Effets et les styles FX<\/li><li>Exporter pour le web, cr\u00e9ation de banni\u00e8res<\/li><li>Exporter pour l\u2019impression OFFSET et num\u00e9rique<\/li><li>Param\u00e9trer le centre de contr\u00f4le pour d\u00e9tecter les erreurs en amont.<\/li><li>Impression en Livret (Imposition des pages pour les documents en vis-\u00e0-vis)<\/li><li>Options d enchainement des textes (veuves et orphelins)<\/li><li>Options de blocs ancr\u00e9s<\/li><li>Hyper liens et r\u00e9f\u00e9rences crois\u00e9es<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<h5 style=\"color:#AEAEAE\">Accessible en visioconf\u00e9rence ou en pr\u00e9sentiel<\/h5>\n<p>Indesign permet de r\u00e9aliser facilement des mises en page magazine, des livres, des brochures, des d\u00e9pliants mais aussi des ebook ainsi que des news-letters \u00e9lectroniques.<\/p>\n","protected":false},"author":1,"featured_media":29797,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[68,70,87,71,65],"tags":[],"table_tags":[],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 14:01:12","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category"},"_links":{"self":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/posts\/87"}],"collection":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/comments?post=87"}],"version-history":[{"count":18,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/posts\/87\/revisions"}],"predecessor-version":[{"id":30347,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/posts\/87\/revisions\/30347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/media\/29797"}],"wp:attachment":[{"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/media?parent=87"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/categories?post=87"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/tags?post=87"},{"taxonomy":"table_tags","embeddable":true,"href":"https:\/\/lesmangeursdetoiles.org\/mangeurs\/wp-json\/wp\/v2\/table_tags?post=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}